{"id":43552,"date":"2023-08-23T15:54:52","date_gmt":"2023-08-23T19:54:52","guid":{"rendered":"https:\/\/www.mastercam.com\/news\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/"},"modified":"2026-01-28T14:50:05","modified_gmt":"2026-01-28T19:50:05","slug":"incontra-il-partner-mastercam-segnalazione-varco","status":"publish","type":"post","link":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/","title":{"rendered":"Incontra il partner Mastercam: Segnalazione VARCO"},"content":{"rendered":"\n<p>L&#8217;automazione domina le conversazioni sul settore manifatturiero ormai da anni, ma per molte aziende &#8211; soprattutto quelle piccole e domestiche con margini di profitto ridotti &#8211; incorporare hardware e software di automazione sembra del tutto fuori questione. Sebbene sia innegabilmente utile, i sistemi di pallet nuovi di zecca con cambiatori robotizzati e sistemi ERP completi sono una chimera per molti piccoli produttori. Per fortuna, alcune soluzioni di automazione sono alla portata di qualsiasi azienda, grande o piccola che sia.  <\/p>\n\n<p>Mastercam \u00e8 sempre stata orgogliosa di collaborare con VARCO Reporting, lo sviluppatore di VARCO Reports. I VARCO Reporting sono esattamente questo tipo di soluzione: una soluzione che riduce le ore di lavoro e gli errori in macchina, elimina i colli di bottiglia della produzione e pu\u00f2 essere adattata a qualsiasi settore o officina. <\/p>\n\n<h2 class=\"wp-block-heading\">Cosa sono i rapporti VARCO?<\/h2>\n\n<p>I pacchetti VARCO Reports sono un componente aggiuntivo di terze parti di Mastercam sviluppato da Jim Varco, programmatore CNC di professione e specialista del supporto MCAM Northwest certificato in pensione. Ha creato la soluzione in risposta a ci\u00f2 che ha visto essere necessario nel settore dopo decenni di lavoro. I report stessi sono stati creati per eliminare le congetture su alcuni punti critici del processo produttivo: la gestione dei dati degli utensili, la gestione dei dati dei materiali e l&#8217;impostazione di macchine e utensili. I report sono attualmente i pi\u00f9 avanzati e configurabili dall&#8217;utente disponibili per Mastercam. Varco li considera un collegamento essenziale tra la programmazione e la gestione delle macchine.    <\/p>\n\n<h2 class=\"wp-block-heading\">Quali sono i vantaggi per gli utenti di Mastercam?<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/10\/VR-Tool.jpg\" alt=\"\" class=\"wp-image-20936\"\/><\/figure>\n\n<p>I tempi di attrezzaggio possono essere la rovina anche dell&#8217;officina di produzione pi\u00f9 efficiente. Semplificare la programmazione e la lavorazione con un potente sistema CAD\/CAM \u00e8 semplice. L&#8217;impostazione tra queste due fasi, tuttavia, pu\u00f2 rappresentare un grosso ostacolo. \u00c8 qui che entrano in gioco i VARCO Report. Questi rapporti possono indirizzare l&#8217;impostazione fino all&#8217;ultimo dettaglio (nome dell&#8217;utensile da taglio, nome del supporto dell&#8217;utensile, posizione del carosello, ecc.    <\/p>\n\n<p>I VARCO Reports offrono agli utenti uno strumento di analisi pi\u00f9 avanzato per i loro processi produttivi. I report disponibili includono elenchi di utensili, elenchi di materiali e fogli di configurazione. I report delle schede di configurazione sono particolarmente utili per gli utenti di Mastercam, in quanto raccolgono e memorizzano i dati di ogni utensile e delle operazioni corrispondenti. Come dice il nome stesso, questo report permette di risparmiare tempo durante l&#8217;impostazione esportando i dati degli utensili direttamente all&#8217;attrezzista. I rapporti Nesting e ATP sono attualmente in fase di sviluppo. I report offrono la possibilit\u00e0 di aggiungere codici a barre e loghi e sono tutti altamente <a href=\"http:\/\/www.varcoreporting.com\/linked\/varco_reporting_activereports_viewer_screenshots-_general.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">personalizzabili<\/a>.     <\/p>\n\n<h2 class=\"wp-block-heading\">Come si usano in Mastercam?<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/10\/VR-Milling.jpg\" alt=\"\" class=\"wp-image-20933\"\/><\/figure>\n\n<p>I VARCO Reports sono programmati utilizzando ActiveReports, lo stesso pacchetto di reporting che attualmente funziona in ogni versione di Mastercam. Ci\u00f2 significa che non c&#8217;\u00e8 possibilit\u00e0 di errori di comunicazione tra VARCO Reports e Mastercam a causa di una cattiva traduzione del codice. Il sistema di reportistica utilizza un&#8217;interfaccia intuitiva in stile Wizard, adatta al puntamento e al clic. Non \u00e8 necessario saper scrivere codice per computer. I pacchetti di reportistica funzionano con qualsiasi prodotto Mastercam dalla X4 alla 2024, compresi i prodotti Mill, Lathe, Wire, Router, Mill-Turn e persino la Learning Edition gratuita. Quando i VARCO Reports vengono mantenuti in manutenzione (che \u00e8 inclusa per il primo anno di VARCO Reports), gli utenti vengono avvisati di tutti gli aggiornamenti disponibili e possono scaricarli e installarli. I VARCO Reports vengono aggiornati in media tra le due e le quattro volte l&#8217;anno, in risposta ai feedback dei clienti e ai nuovi lanci di Mastercam.      <\/p>\n\n<h2 class=\"wp-block-heading\">Prova tu stesso!<\/h2>\n\n<p>Se sei curioso di vedere come VARCO Reports funziona con le tue operazioni, visita il sito web di VARCO Reporting e scarica la <a href=\"http:\/\/www.varcoreporting.com\/varco_reporting_005.htm\" target=\"_blank\" rel=\"noreferrer noopener\">versione gratuita oggi stesso<\/a>. Se non utilizzi Mastercam, puoi abbinare il VARCO Reports gratuito alla Mastercam <a href=\"https:\/\/signup.mastercam.com\/demo-hle\" target=\"_blank\" rel=\"noreferrer noopener\">Learning Edition<\/a>. <\/p>\n\n<p>VARCO Reporting invita gli utenti con richieste specifiche a <a href=\"http:\/\/varcoreporting.com\/support.php\" target=\"_blank\" rel=\"noreferrer noopener\">contattarci<\/a>. Sebbene i modelli di VARCO Reports siano altamente personalizzabili, il suo team \u00e8 sempre aperto alla creazione di modelli speciali per i clienti. <\/p>\n\n<p>Sei pronto a installare VARCO Reports, Mastercam o entrambi? Parla con il tuo <a href=\"https:\/\/www.mastercam.com\/it\/?page_id=42729\" target=\"_blank\" rel=\"noreferrer noopener\">rivenditore Mastercam<\/a> locale oggi stesso! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;automazione domina le conversazioni sul settore manifatturiero ormai da anni, ma per molte aziende &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43554,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[642],"tags":[620,619,623,680,621,694],"class_list":["post-43552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-partnership","tag-cad-cam","tag-lavorazione-cnc","tag-lavorazioni-meccaniche","tag-macchinisti","tag-produzione","tag-rapporti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>%<\/title>\n<meta name=\"description\" content=\"Incorporare l&#039;automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all&#039;ultimo dettaglio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"%\" \/>\n<meta property=\"og:description\" content=\"Incorporare l&#039;automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all&#039;ultimo dettaglio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\" \/>\n<meta property=\"og:site_name\" content=\"mastercam.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mastercam\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T19:54:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T19:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mastercam\" \/>\n<meta name=\"twitter:site\" content=\"@mastercam\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b\"},\"headline\":\"Incontra il partner Mastercam: Segnalazione VARCO\",\"datePublished\":\"2023-08-23T19:54:52+00:00\",\"dateModified\":\"2026-01-28T19:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\"},\"wordCount\":697,\"publisher\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg\",\"keywords\":[\"cad\/cam\",\"Lavorazione CNC\",\"Lavorazioni meccaniche\",\"macchinisti\",\"Produzione\",\"rapporti\"],\"articleSection\":[\"Partnership\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\",\"url\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\",\"name\":\"%\",\"isPartOf\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg\",\"datePublished\":\"2023-08-23T19:54:52+00:00\",\"dateModified\":\"2026-01-28T19:50:05+00:00\",\"description\":\"Incorporare l'automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all'ultimo dettaglio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg\",\"width\":680,\"height\":680,\"caption\":\"Varco Reports logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mastercam.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontra il partner Mastercam: Segnalazione VARCO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"name\":\"Mastercam\",\"description\":\"Creating software and services that solve the world&#039;s manufacturing challenges\",\"publisher\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mastercam.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\",\"name\":\"Mastercam\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"width\":230,\"height\":40,\"caption\":\"Mastercam\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Mastercam\/\",\"https:\/\/x.com\/mastercam\",\"https:\/\/www.linkedin.com\/company\/mastercam\",\"https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw\",\"https:\/\/www.instagram.com\/mastercam\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"%","description":"Incorporare l'automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all'ultimo dettaglio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/","og_locale":"it_IT","og_type":"article","og_title":"%","og_description":"Incorporare l'automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all'ultimo dettaglio.","og_url":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/","og_site_name":"mastercam.com","article_publisher":"https:\/\/www.facebook.com\/Mastercam\/","article_published_time":"2023-08-23T19:54:52+00:00","article_modified_time":"2026-01-28T19:50:05+00:00","og_image":[{"width":680,"height":680,"url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@mastercam","twitter_site":"@mastercam","twitter_misc":{"Written by":"admin","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#article","isPartOf":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/"},"author":{"name":"admin","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b"},"headline":"Incontra il partner Mastercam: Segnalazione VARCO","datePublished":"2023-08-23T19:54:52+00:00","dateModified":"2026-01-28T19:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/"},"wordCount":697,"publisher":{"@id":"https:\/\/www.mastercam.com\/it\/#organization"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg","keywords":["cad\/cam","Lavorazione CNC","Lavorazioni meccaniche","macchinisti","Produzione","rapporti"],"articleSection":["Partnership"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/","url":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/","name":"%","isPartOf":{"@id":"https:\/\/www.mastercam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg","datePublished":"2023-08-23T19:54:52+00:00","dateModified":"2026-01-28T19:50:05+00:00","description":"Incorporare l'automazione pu\u00f2 sembrare un compito scoraggiante, ma continua a leggere per scoprire come VARCO Reports pu\u00f2 dirigere la configurazione fino all'ultimo dettaglio.","breadcrumb":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#primaryimage","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/08\/imageedit_14_6798357332.jpg","width":680,"height":680,"caption":"Varco Reports logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/incontra-il-partner-mastercam-segnalazione-varco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mastercam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Incontra il partner Mastercam: Segnalazione VARCO"}]},{"@type":"WebSite","@id":"https:\/\/www.mastercam.com\/it\/#website","url":"https:\/\/www.mastercam.com\/it\/","name":"Mastercam","description":"Creating software and services that solve the world&#039;s manufacturing challenges","publisher":{"@id":"https:\/\/www.mastercam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mastercam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mastercam.com\/it\/#organization","name":"Mastercam","url":"https:\/\/www.mastercam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","width":230,"height":40,"caption":"Mastercam"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mastercam\/","https:\/\/x.com\/mastercam","https:\/\/www.linkedin.com\/company\/mastercam","https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw","https:\/\/www.instagram.com\/mastercam\/"]},{"@type":"Person","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts\/43552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/comments?post=43552"}],"version-history":[{"count":0,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts\/43552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media\/43554"}],"wp:attachment":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media?parent=43552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/categories?post=43552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/tags?post=43552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}