{"id":42819,"date":"2022-04-26T15:16:45","date_gmt":"2022-04-26T19:16:45","guid":{"rendered":"https:\/\/www.mastercam.com\/news\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/"},"modified":"2026-01-28T14:44:08","modified_gmt":"2026-01-28T19:44:08","slug":"tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione","status":"publish","type":"post","link":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/","title":{"rendered":"Tutto quello che c&#8217;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Che cos&#8217;\u00e8 lo stampaggio a iniezione?<\/h2>\n\n<p class=\"wp-block-paragraph\">Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8 ottimizzato per massimizzare i risparmi sui costi e la produzione dei pezzi. Per prima cosa, il materiale in pellet viene inserito in un contenitore riscaldato per diventare fuso. Viene mescolato con una vite elicoidale per mantenere una consistenza omogenea e per accelerare il processo di riscaldamento. Il liquido viene poi pompato &#8211; o iniettato &#8211; con uno stantuffo in uno stampo preconfezionato, che modella il materiale nella forma desiderata mentre si raffredda e si indurisce. A volte un altro componente viene inserito nella cavit\u00e0 dello stampo mentre il materiale si raffredda, in un processo chiamato stampaggio a inserti. Questo aggiunge un ulteriore livello di complessit\u00e0 allo stampo. Nella maggior parte dei casi, lo stampaggio a iniezione viene effettuato con la termoplastica, una plastica composta da resine polimeriche progettate per ammorbidirsi o liquefarsi quando vengono riscaldate. Meno comunemente si utilizzano polimeri termoindurenti, metalli e vetri.        <\/p>\n\n<h2 class=\"wp-block-heading\">Quali sono i vantaggi della produzione di stampi a iniezione?<\/h2>\n\n<p class=\"wp-block-paragraph\">La produzione di stampi a iniezione \u00e8 il modo migliore per produrre in massa prodotti in plastica ed \u00e8 il metodo predominante negli Stati Uniti. Le materie termoplastiche sono incredibilmente versatili e convenienti. Permettono di produrre qualsiasi cosa, dai comuni oggetti domestici come tazze e pettini ai componenti automobilistici altamente specializzati. Lo stampaggio a iniezione \u00e8 pi\u00f9 efficiente per le aziende che producono alti volumi e bassa variet\u00e0 di pezzi con tolleranze ridotte che potrebbero richiedere una lavorazione.  <\/p>\n\n<h2 class=\"wp-block-heading\">Quali sono le applicazioni della lavorazione CNC per la produzione di stampi a iniezione?<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"503\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/mold-core.jpeg\" alt=\"\" class=\"wp-image-10414\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/mold-core.jpeg 650w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/mold-core-300x232.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/mold-core-112x87.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/mold-core-224x173.jpeg 224w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Mentre le tolleranze del prodotto finito potrebbero non richiedere la lavorazione CNC, gli stampi stessi lo fanno, soprattutto quelli con geometrie e contorni interni complessi. La <a href=\"https:\/\/www.mastercam.com\/it\/news\/blog\/macchine-cnc-orizzontali-e-verticali-quali-sono-le-differenze\/\">lavorazione CNC<\/a> \u00e8 lo stile di produzione principale per la costruzione di stampi. Gli stampi sono pi\u00f9 comunemente lavorati in acciaio per utensili e acciaio inossidabile, ma occasionalmente viene utilizzato anche l&#8217;alluminio. L&#8217;alluminio non resiste all&#8217;usura dello stampaggio a iniezione come l&#8217;acciaio, ma \u00e8 un&#8217;alternativa economica per piccoli lotti di pezzi stampati a iniezione.  <\/p>\n\n<p class=\"wp-block-paragraph\">Gli stampi in acciaio devono essere in grado di mantenere le dimensioni esatte e i contorni interni nel corso di migliaia o milioni di cicli di iniezione, con tutto il calore e le sollecitazioni che ne conseguono. La lavorazione CNC rende semplice la lavorazione di questi metalli con le tolleranze desiderate. <\/p>\n\n<p class=\"wp-block-paragraph\">Meno frequentemente, la lavorazione CNC viene utilizzata per la finitura di pezzi stampati a iniezione. Durante il processo di stampaggio, \u00e8 comune che i pezzi presentino linee di demarcazione, segni di cancello e fessure del perno di espulsione. Una volta raffreddati e induriti, i pezzi possono essere lavorati per rimuovere questi difetti. Dopo la lavorazione, le finiture superficiali saranno molto migliori, il che pu\u00f2 essere importante per i pezzi che sono apprezzati dal punto di vista estetico.   <\/p>\n\n<h2 class=\"wp-block-heading\">Capacit\u00e0 di lavorazione CNC Mastercam per lo stampaggio a iniezione<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"459\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/Accelerated-finishing.jpeg\" alt=\"\" class=\"wp-image-10419\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/Accelerated-finishing.jpeg 650w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/Accelerated-finishing-300x212.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/Accelerated-finishing-112x79.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/05\/Accelerated-finishing-224x158.jpeg 224w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Il software CAD\/CAM Mastercam si \u00e8 evoluto nel corso dei decenni fino a diventare lo strumento perfetto per la progettazione e la lavorazione degli stampi.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Le soluzioni di elettroerosione a filo forniscono percorsi utensile avanzati e specializzati per l&#8217;industria degli stampi.<\/li>\n\n\n\n<li>I software CAD intuitivi danno agli utenti la possibilit\u00e0 di importare, modificare o creare quasi tutte le geometrie.<\/li>\n\n\n\n<li>Programmare <a href=\"http:\/\/www.mastercam.com\/5-ways-to-improve-productivity-with-5-axis-machining\/\">macchine a 4 e 5 assi<\/a> per tagliare forme complesse senza bisogno di configurazioni multiple \u00e8 facile con Multiaxis.<\/li>\n\n\n\n<li>I percorsi utensile di finitura e sbavatura accelerati riducono notevolmente il tempo di lavoro al banco.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Per saperne di pi\u00f9<\/h2>\n\n<p class=\"wp-block-paragraph\">Sei pronto a portare Mastercam nella tua officina di costruzione stampi? Contatta il tuo <a href=\"https:\/\/www.mastercam.com\/it\/?page_id=42729\">rivenditore locale qui.<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che cos&#8217;\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[615],"tags":[],"class_list":["post-42819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prodotto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tutto quello che c&#039;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com<\/title>\n<meta name=\"description\" content=\"Che cos&#039;\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutto quello che c&#039;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com\" \/>\n<meta property=\"og:description\" content=\"Che cos&#039;\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\" \/>\n<meta property=\"og:site_name\" content=\"mastercam.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mastercam\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T19:16:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T19:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mastercam\" \/>\n<meta name=\"twitter:site\" content=\"@mastercam\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b\"},\"headline\":\"Tutto quello che c&#8217;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione\",\"datePublished\":\"2022-04-26T19:16:45+00:00\",\"dateModified\":\"2026-01-28T19:44:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\"},\"wordCount\":617,\"publisher\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg\",\"articleSection\":[\"Prodotto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\",\"url\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\",\"name\":\"Tutto quello che c'\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg\",\"datePublished\":\"2022-04-26T19:16:45+00:00\",\"dateModified\":\"2026-01-28T19:44:08+00:00\",\"description\":\"Che cos'\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg\",\"width\":650,\"height\":492,\"caption\":\"Console\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mastercam.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutto quello che c&#8217;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"name\":\"Mastercam\",\"description\":\"Creating software and services that solve the world&#039;s manufacturing challenges\",\"publisher\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mastercam.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\",\"name\":\"Mastercam\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"width\":230,\"height\":40,\"caption\":\"Mastercam\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Mastercam\/\",\"https:\/\/x.com\/mastercam\",\"https:\/\/www.linkedin.com\/company\/mastercam\",\"https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw\",\"https:\/\/www.instagram.com\/mastercam\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutto quello che c'\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com","description":"Che cos'\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/","og_locale":"it_IT","og_type":"article","og_title":"Tutto quello che c'\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com","og_description":"Che cos'\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8","og_url":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/","og_site_name":"mastercam.com","article_publisher":"https:\/\/www.facebook.com\/Mastercam\/","article_published_time":"2022-04-26T19:16:45+00:00","article_modified_time":"2026-01-28T19:44:08+00:00","og_image":[{"width":650,"height":492,"url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@mastercam","twitter_site":"@mastercam","twitter_misc":{"Written by":"admin","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#article","isPartOf":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/"},"author":{"name":"admin","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b"},"headline":"Tutto quello che c&#8217;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione","datePublished":"2022-04-26T19:16:45+00:00","dateModified":"2026-01-28T19:44:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/"},"wordCount":617,"publisher":{"@id":"https:\/\/www.mastercam.com\/it\/#organization"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg","articleSection":["Prodotto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/","url":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/","name":"Tutto quello che c'\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione - mastercam.com","isPartOf":{"@id":"https:\/\/www.mastercam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg","datePublished":"2022-04-26T19:16:45+00:00","dateModified":"2026-01-28T19:44:08+00:00","description":"Che cos'\u00e8 lo stampaggio a iniezione? Lo stampo a iniezione \u00e8 il metodo preferito per la produzione di massa di parti in plastica. Il processo \u00e8","breadcrumb":{"@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#primaryimage","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2022\/04\/Console-MC.jpg","width":650,"height":492,"caption":"Console"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mastercam.com\/it\/community\/blog\/tutto-quello-che-ce-da-sapere-sulla-lavorazione-cnc-per-la-produzione-di-stampi-a-iniezione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mastercam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tutto quello che c&#8217;\u00e8 da sapere sulla lavorazione CNC per la produzione di stampi a iniezione"}]},{"@type":"WebSite","@id":"https:\/\/www.mastercam.com\/it\/#website","url":"https:\/\/www.mastercam.com\/it\/","name":"Mastercam","description":"Creating software and services that solve the world&#039;s manufacturing challenges","publisher":{"@id":"https:\/\/www.mastercam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mastercam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mastercam.com\/it\/#organization","name":"Mastercam","url":"https:\/\/www.mastercam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","width":230,"height":40,"caption":"Mastercam"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mastercam\/","https:\/\/x.com\/mastercam","https:\/\/www.linkedin.com\/company\/mastercam","https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw","https:\/\/www.instagram.com\/mastercam\/"]},{"@type":"Person","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/f7647f4af443218885432a87b9653e1b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b72bdabc350ddd16040250e47e30c6f0af9df399c19d38a7ede0d3b9cedf996f?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts\/42819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/comments?post=42819"}],"version-history":[{"count":0,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/posts\/42819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media\/42824"}],"wp:attachment":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media?parent=42819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/categories?post=42819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/tags?post=42819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}