{"id":42943,"date":"2023-04-18T15:19:22","date_gmt":"2023-04-18T19:19:22","guid":{"rendered":"https:\/\/www.mastercam.com\/success-stories\/grayco-machine-ltd\/"},"modified":"2026-01-28T14:45:23","modified_gmt":"2026-01-28T19:45:23","slug":"grayco-machine-ltd","status":"publish","type":"casestudy","link":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/","title":{"rendered":"Grayco Machine Ltd."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L&#8217;officina ottiene un aumento della produzione grazie al software CAD\/CAM<\/h2>\n\n<p>Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce componenti per l&#8217;industria agricola e petrolifera. Utilizzando Mastercam come solida piattaforma CAD\/CAM per le attivit\u00e0 di produzione, l&#8217;azienda \u00e8 specializzata nella produzione di pignoni e ingranaggi per i martinetti delle pompe e di argani per le trivellazioni petrolifere. <\/p>\n\n<h2 class=\"wp-block-heading\">Fatti rapidi<\/h2>\n\n<p><strong>Prodotto utilizzato:<\/strong> Filo, tornio, fresa<\/p>\n\n<p><strong>Industria:<\/strong> Industria pesante, Energia, Negozio di lavoro<\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-1024x356.jpeg\" alt=\"Cinque dipendenti maschi di Grayco Machine nel loro magazzino\" class=\"wp-image-8583\" width=\"1363\" height=\"474\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-1024x356.jpeg 1024w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-300x104.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-768x267.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-112x39.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1-224x78.jpeg 224w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg 1440w\" sizes=\"auto, (max-width: 1363px) 100vw, 1363px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Dettagli del progetto:<\/h2>\n\n<ul class=\"wp-block-list\"><li><strong>La sfida:<\/strong> Raggiungere tassi di produzione sani e qualit\u00e0 dei prodotti in un periodo di incertezza economica.<\/li><li><strong>La soluzione:<\/strong> Mastercam, il software CNC pi\u00f9 diffuso per le operazioni CAD\/CAM<\/li><li><strong>I vantaggi:<\/strong><ul><li>Per creare geometrie complesse per gli ingranaggi, il software CAM genera il codice G degli ingranaggi, i profili e le forme dei denti.<\/li><li>Dalla contornatura di base a 2 assi al movimento complesso a 4 assi, il software Mastercam Wire supporta percorsi di filo potenti e tecniche di taglio efficienti.<\/li><li>Gli strumenti di verifica del percorso utensile assicurano che il movimento del percorso utensile raggiunga i risultati previsti, riducendo al minimo la sgrossatura.<\/li><li>I controlli di collisione consentono ai programmatori di determinare quando \u00e8 necessario cambiare utensile e di visualizzare in anteprima le finiture dei pezzi.<\/li><li>Il software CAM offre la flessibilit\u00e0 necessaria per produrre una variet\u00e0 di geometrie e dimensioni di pezzi.<\/li><\/ul><\/li><\/ul>\n\n<p>Nonostante la continua volatilit\u00e0 dell&#8217;industria petrolifera, l&#8217;officina si mantiene a galla grazie alla visione del suo proprietario, Graham Peterson. Peterson \u00e8 un macchinista specializzato Red Seal e un sostenitore di lunga data dei programmi di lavorazione e di apprendistato. Tutti i dipendenti <a href=\"http:\/\/graycomachine.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">di Grayco<\/a> sono macchinisti professionisti Red Seal altamente qualificati, con una buona conoscenza delle operazioni di macchina sia manuali che CNC.  <\/p>\n\n<p>La struttura di Grayco, che si estende su 9.000 metri quadrati, ospita frese e torni manuali e CNC, elettroerosioni e frese a spina di pesce Sykes. Ultimamente, l&#8217;elettroerosione a filo \u00e8 stata particolarmente impegnata. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-1024x768.jpeg\" alt=\"Schermo CHMER-EDM\" class=\"wp-image-8588\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-1024x768.jpeg 1024w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-300x225.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-768x576.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-112x84.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2-224x168.jpeg 224w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/CHMER-EDM-1536x1152-2.jpeg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>&#8220;Utilizziamo il filo per realizzare scanalature interne ed esterne e molti denti di ingranaggi&#8221;, afferma Peterson. &#8220;Questi pezzi sono programmati con il software CAM perch\u00e9 lo usiamo per generare tutti i profili&#8221;. <\/p>\n\n<p>Per produrre ingranaggi, i programmatori utilizzano un&#8217;elettroerosione a filo abbinata al software CAM di Mastercam. Dalla contornatura di base a 2 assi al movimento complesso a 4 assi, il software <a href=\"https:\/\/www.mastercam.com\/solutions\/wire\/\">Mastercam Wire<\/a> supporta potenti percorsi di filo e tecniche di taglio efficienti. La modellazione CAD 3D completa, le strategie automatiche di lead-in e lead-out e il taglio semplificato di pi\u00f9 parti sono caratteristiche del flessibile pacchetto software. Il software Wire permette di controllare il movimento del filo, l&#8217;angolo, le entrate, le uscite e molto altro. La tracciabilit\u00e0 dei file e il riconoscimento delle modifiche consentono una programmazione e una riprogrammazione semplici. Gli elementi del lavoro possono essere modificati e i percorsi del filo aggiornati senza riavvii.     <\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1.jpeg\" alt=\"Ingranaggio cilindrico in metallo argentato\" class=\"wp-image-8594\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1.jpeg 1024w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1-300x225.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1-768x576.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1-112x84.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Involute-spur-gear-1-224x168.jpeg 224w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Gli ingranaggi Sykes a spina di pesce fanno parte della produzione di ingranaggi di Grayco. Per creare geometrie complesse, i programmatori si affidano al software CAM per generare il codice G degli ingranaggi, i profili dei denti e le forme. <\/p>\n\n<p>&#8220;Usiamo il software quasi esclusivamente per programmare le nostre macchine&#8221;, ha detto Peterson. &#8220;Stiamo affrontando programmi e profili di pezzi sempre pi\u00f9 difficili. Non possiamo pi\u00f9 farlo a mano&#8221;. <\/p>\n\n<p>Per produrre pezzi dalle forme complesse, i programmatori si affidano alle elettroerosioni a filo e al software che le gestisce. Gli strumenti di verifica Wirepath di Mastercam assicurano che il movimento del percorso utensile raggiunga i risultati desiderati. Nel caso degli ingranaggi Grayco, la sgrossatura \u00e8 ridotta al minimo. Di solito bastano una passata di sgrossatura e una di finitura per completare il processo di produzione degli ingranaggi. Si ottengono tolleranze di finitura superficiale comprese tra 64 Ra (rugosit\u00e0 media) e 8 Ra.    <\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Sykes-Gear-1.jpeg\" alt=\"Ingranaggio sykes in metallo argentato\" class=\"wp-image-8599\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Sykes-Gear-1.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Sykes-Gear-1-225x300.jpeg 225w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Sykes-Gear-1-84x112.jpeg 84w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Sykes-Gear-1-168x224.jpeg 168w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n<p>&#8220;Mastercam ci aiuta a ottenere un percorso a filo molto preciso, soprattutto sui denti degli ingranaggi&#8221;, afferma Jerry Deneve, macchinista Grayco Machine Red Seal e programmatore CNC. &#8220;Possiamo arrivare fino alle tolleranze di rettifica con l&#8217;elettroerosione a filo e soddisfare i requisiti di finitura superficiale con l&#8217;aiuto del software&#8221;. <\/p>\n\n<p>I tempi di consegna sono un fattore determinante. I lavori in arrivo richiedono la produzione di pezzi one-up o two-up. Un&#8217;idea del cliente passa dal blocco e dalla carta, a Mastercam e al pezzo finito in tempi brevi.  <\/p>\n\n<p>&#8220;Alcuni dei lavori che facciamo non si possono programmare a mano con un blocco note&#8221;, ha detto Peterson. &#8220;Hai bisogno di Mastercam per creare questo tipo di profili, forme e programmi per l&#8217;elettroerosione&#8221;. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-1024x768.jpeg\" alt=\"Strumento per il down hole in metallo argentato\" class=\"wp-image-8604\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-1024x768.jpeg 1024w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-300x225.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-768x576.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-112x84.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2-224x168.jpeg 224w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Down-hole-tool-1536x1152-2.jpeg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Il software CAM offre a Grayco la flessibilit\u00e0 di produrre una variet\u00e0 di geometrie e dimensioni di pezzi. Se un pezzo \u00e8 troppo grande per essere montato su una macchina, ad esempio, un operatore pu\u00f2 lavorare su un angolo del pezzo alla volta. Pu\u00f2 programmare quell&#8217;angolo, ruotare il pezzo, girare il modello con Mastercam, reinserirlo e ripartire.  <\/p>\n\n<p>Grayco appalta la modellazione delle superfici dei suoi ingranaggi a spina di pesce, ma ha intenzione di spostare la produzione sulle fresatrici. L&#8217;avanzamento attuale della fresa \u00e8 di 200 pollici al minuto; Grayco intende acquistare una macchina in grado di gestire 300 piedi di superficie al minuto con velocit\u00e0 di 20.000 giri al minuto per ottenere la precisione della finitura superficiale richiesta. <\/p>\n\n<p>&#8220;Sappiamo che \u00e8 l\u00ec che dobbiamo andare&#8221;, ha detto Deneve a proposito dell&#8217;aggiornamento dell&#8217;officina. &#8220;Lo abbiamo fatto in nove modi con le vecchie macchine, ma ora dobbiamo modernizzarci con le superfici e la modellazione 3D per passare a un livello diverso&#8221;. <\/p>\n\n<p>Da quando utilizza Mastercam, Grayco ha realizzato pezzi migliori e pi\u00f9 complicati a un ritmo pi\u00f9 veloce. La modernizzazione di questa piccola ma potente officina \u00e8 stata possibile grazie ai vantaggi offerti dal software CAM. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-1024x1024.jpeg\" alt=\"2 giunti di trasmissione in metallo argentato\" class=\"wp-image-8609\" srcset=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-1024x1024.jpeg 1024w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-150x150.jpeg 150w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-300x300.jpeg 300w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-768x768.jpeg 768w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-112x112.jpeg 112w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1-224x224.jpeg 224w, https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/Drive-couplings-1.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h5 class=\"wp-block-heading\">Preventivo del cliente<\/h5>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Alcuni lavori che facciamo non si possono programmare a mano con un blocco note. Hai bisogno di Mastercam per creare quel tipo di profili, forme e programmi per l&#8217;elettroerosione. E questo ci riporta ad essere un&#8217;officina che cerca di fare le cose in fretta&#8221;.<\/p><cite>&#8211; Graham Peterson, Proprietario, Grayco Machine Ltd., Leduc, Alberta, Canada<\/cite><\/blockquote>\n","protected":false},"featured_media":42955,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"industry":[],"class_list":["post-42943","casestudy","type-casestudy","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grayco Machine Ltd. - mastercam.com<\/title>\n<meta name=\"description\" content=\"L&#039;officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grayco Machine Ltd. - mastercam.com\" \/>\n<meta property=\"og:description\" content=\"L&#039;officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/\" \/>\n<meta property=\"og:site_name\" content=\"mastercam.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mastercam\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T19:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mastercam\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/\",\"url\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/\",\"name\":\"Grayco Machine Ltd. - mastercam.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg\",\"datePublished\":\"2023-04-18T19:19:22+00:00\",\"dateModified\":\"2026-01-28T19:45:23+00:00\",\"description\":\"L'officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg\",\"width\":1440,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mastercam.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grayco Machine Ltd.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#website\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"name\":\"Mastercam\",\"description\":\"Creating software and services that solve the world&#039;s manufacturing challenges\",\"publisher\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mastercam.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#organization\",\"name\":\"Mastercam\",\"url\":\"https:\/\/www.mastercam.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"contentUrl\":\"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg\",\"width\":230,\"height\":40,\"caption\":\"Mastercam\"},\"image\":{\"@id\":\"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Mastercam\/\",\"https:\/\/x.com\/mastercam\",\"https:\/\/www.linkedin.com\/company\/mastercam\",\"https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw\",\"https:\/\/www.instagram.com\/mastercam\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grayco Machine Ltd. - mastercam.com","description":"L'officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/","og_locale":"it_IT","og_type":"article","og_title":"Grayco Machine Ltd. - mastercam.com","og_description":"L'officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce","og_url":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/","og_site_name":"mastercam.com","article_publisher":"https:\/\/www.facebook.com\/Mastercam\/","article_modified_time":"2026-01-28T19:45:23+00:00","og_image":[{"width":1440,"height":500,"url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mastercam","twitter_misc":{"Est. reading time":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/","url":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/","name":"Grayco Machine Ltd. - mastercam.com","isPartOf":{"@id":"https:\/\/www.mastercam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg","datePublished":"2023-04-18T19:19:22+00:00","dateModified":"2026-01-28T19:45:23+00:00","description":"L'officina ottiene un aumento della produzione grazie al software CAD\/CAM Fondata nel 1997, Grayco Machine Ltd., a Leduc, Alberta, Canada, produce","breadcrumb":{"@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#primaryimage","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/04\/GraycoMachine-1.jpeg","width":1440,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.mastercam.com\/it\/success-stories\/grayco-machine-ltd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mastercam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Grayco Machine Ltd."}]},{"@type":"WebSite","@id":"https:\/\/www.mastercam.com\/it\/#website","url":"https:\/\/www.mastercam.com\/it\/","name":"Mastercam","description":"Creating software and services that solve the world&#039;s manufacturing challenges","publisher":{"@id":"https:\/\/www.mastercam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mastercam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mastercam.com\/it\/#organization","name":"Mastercam","url":"https:\/\/www.mastercam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","contentUrl":"https:\/\/www.mastercam.com\/wp-content\/uploads\/2023\/02\/MC_logo.svg","width":230,"height":40,"caption":"Mastercam"},"image":{"@id":"https:\/\/www.mastercam.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mastercam\/","https:\/\/x.com\/mastercam","https:\/\/www.linkedin.com\/company\/mastercam","https:\/\/www.youtube.com\/channel\/UChJt5ruSkqnmFH44WsXVZLw","https:\/\/www.instagram.com\/mastercam\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/casestudy\/42943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/casestudy"}],"about":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/types\/casestudy"}],"version-history":[{"count":0,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/casestudy\/42943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media\/42955"}],"wp:attachment":[{"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/media?parent=42943"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.mastercam.com\/it\/wp-json\/wp\/v2\/industry?post=42943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}